{"id":3842,"date":"2025-10-29T14:55:29","date_gmt":"2025-10-29T17:55:29","guid":{"rendered":"https:\/\/emc.mg.gov.br\/institucional\/?p=3842"},"modified":"2025-10-29T14:56:22","modified_gmt":"2025-10-29T17:56:22","slug":"integrantes-da-banda-pato-fu-no-agenda-da-rede-minas-nesta-quarta-29","status":"publish","type":"post","link":"https:\/\/emc.mg.gov.br\/institucional\/integrantes-da-banda-pato-fu-no-agenda-da-rede-minas-nesta-quarta-29\/","title":{"rendered":"Integrantes da banda Pato Fu no Agenda, da Rede Minas, nesta quarta (29)"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" width=\"300\" height=\"235\" src=\"https:\/\/emc.mg.gov.br\/institucional\/wp-content\/uploads\/2025\/10\/THUMB-SITE-REDE-MINAS-E-EMC7.png\" alt=\"\" class=\"wp-image-3843\"\/><\/figure><\/div>\n\n\n<p>John Ulh\u00f4a e Richard Neves foram os convidados do Agenda, da Rede Minas. Os m\u00fasicos da banda Pato Fu falam sobre a participa\u00e7\u00e3o na trilha do filme \u201cO \u00daltimo Epis\u00f3dio&#8221;, da produtora \u201cFilmes de Pl\u00e1stico\u201d.<\/p>\n\n\n\n<p>A trilha sonora, assinada pelos integrantes do grupo, marca um ponto importante na carreira dos artistas e aposta nas mem\u00f3rias da adolesc\u00eancia. No bate-papo com Dani Vargas, eles comentaram, ainda, sobre o lan\u00e7amento do vinil com as m\u00fasicas do longa mineiro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>John Ulh\u00f4a e Richard Neves foram os convidados do Agenda, da Rede Minas. Os m\u00fasicos da banda Pato Fu falam sobre a participa\u00e7\u00e3o na trilha do filme \u201cO \u00daltimo Epis\u00f3dio&#8221;, da produtora \u201cFilmes de Pl\u00e1stico\u201d. A trilha sonora, assinada pelos integrantes do grupo, marca um ponto importante na carreira dos artistas e aposta nas mem\u00f3rias [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3845,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ub_ctt_via":""},"categories":[15],"tags":[],"featured_image_src":"https:\/\/emc.mg.gov.br\/institucional\/wp-content\/uploads\/2025\/10\/THUMB-SITE-REDE-MINAS-E-EMC7-1.png","author_info":{"display_name":"Administrador Site EMC","author_link":"https:\/\/emc.mg.gov.br\/institucional\/author\/emc_adminweb\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.5.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Integrantes da banda Pato Fu no Agenda, da Rede Minas, nesta quarta (29) - EMC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/emc.mg.gov.br\/institucional\/integrantes-da-banda-pato-fu-no-agenda-da-rede-minas-nesta-quarta-29\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Integrantes da banda Pato Fu no Agenda, da Rede Minas, nesta quarta (29) - EMC\" \/>\n<meta property=\"og:description\" content=\"John Ulh\u00f4a e Richard Neves foram os convidados do Agenda, da Rede Minas. Os m\u00fasicos da banda Pato Fu falam sobre a participa\u00e7\u00e3o na trilha do filme \u201cO \u00daltimo Epis\u00f3dio&#8221;, da produtora \u201cFilmes de Pl\u00e1stico\u201d. A trilha sonora, assinada pelos integrantes do grupo, marca um ponto importante na carreira dos artistas e aposta nas mem\u00f3rias [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/emc.mg.gov.br\/institucional\/integrantes-da-banda-pato-fu-no-agenda-da-rede-minas-nesta-quarta-29\/\" \/>\n<meta property=\"og:site_name\" content=\"EMC\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-29T17:55:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-29T17:56:22+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/emc.mg.gov.br\/institucional\/wp-content\/uploads\/2025\/10\/THUMB-SITE-REDE-MINAS-E-EMC7-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"235\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Administrador Site EMC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administrador Site EMC\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/emc.mg.gov.br\/institucional\/integrantes-da-banda-pato-fu-no-agenda-da-rede-minas-nesta-quarta-29\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/emc.mg.gov.br\/institucional\/integrantes-da-banda-pato-fu-no-agenda-da-rede-minas-nesta-quarta-29\/\"},\"author\":{\"name\":\"Administrador Site EMC\",\"@id\":\"http:\/\/emc.mg.gov.br\/institucional\/#\/schema\/person\/b3c1372ae3ed1f53d53d7ebb7048c1a1\"},\"headline\":\"Integrantes da banda Pato Fu no Agenda, da Rede Minas, nesta quarta (29)\",\"datePublished\":\"2025-10-29T17:55:29+00:00\",\"dateModified\":\"2025-10-29T17:56:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/emc.mg.gov.br\/institucional\/integrantes-da-banda-pato-fu-no-agenda-da-rede-minas-nesta-quarta-29\/\"},\"wordCount\":97,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\/\/emc.mg.gov.br\/institucional\/#organization\"},\"articleSection\":[\"Destaques\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/emc.mg.gov.br\/institucional\/integrantes-da-banda-pato-fu-no-agenda-da-rede-minas-nesta-quarta-29\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/emc.mg.gov.br\/institucional\/integrantes-da-banda-pato-fu-no-agenda-da-rede-minas-nesta-quarta-29\/\",\"url\":\"http:\/\/emc.mg.gov.br\/institucional\/integrantes-da-banda-pato-fu-no-agenda-da-rede-minas-nesta-quarta-29\/\",\"name\":\"Integrantes da banda Pato Fu no Agenda, da Rede Minas, nesta quarta (29) - EMC\",\"isPartOf\":{\"@id\":\"http:\/\/emc.mg.gov.br\/institucional\/#website\"},\"datePublished\":\"2025-10-29T17:55:29+00:00\",\"dateModified\":\"2025-10-29T17:56:22+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/emc.mg.gov.br\/institucional\/integrantes-da-banda-pato-fu-no-agenda-da-rede-minas-nesta-quarta-29\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/emc.mg.gov.br\/institucional\/integrantes-da-banda-pato-fu-no-agenda-da-rede-minas-nesta-quarta-29\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/emc.mg.gov.br\/institucional\/integrantes-da-banda-pato-fu-no-agenda-da-rede-minas-nesta-quarta-29\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\/\/emc.mg.gov.br\/institucional\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Integrantes da banda Pato Fu no Agenda, da Rede Minas, nesta quarta (29)\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/emc.mg.gov.br\/institucional\/#website\",\"url\":\"http:\/\/emc.mg.gov.br\/institucional\/\",\"name\":\"EMC\",\"description\":\"Empresa Mineira de Comunica\u00e7\u00e3o\",\"publisher\":{\"@id\":\"http:\/\/emc.mg.gov.br\/institucional\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/emc.mg.gov.br\/institucional\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/emc.mg.gov.br\/institucional\/#organization\",\"name\":\"EMC\",\"url\":\"http:\/\/emc.mg.gov.br\/institucional\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/emc.mg.gov.br\/institucional\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/emc.mg.gov.br\/institucional\/wp-content\/uploads\/2022\/06\/EMCmarca.png\",\"contentUrl\":\"https:\/\/emc.mg.gov.br\/institucional\/wp-content\/uploads\/2022\/06\/EMCmarca.png\",\"width\":133,\"height\":89,\"caption\":\"EMC \"},\"image\":{\"@id\":\"http:\/\/emc.mg.gov.br\/institucional\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\/\/emc.mg.gov.br\/institucional\/#\/schema\/person\/b3c1372ae3ed1f53d53d7ebb7048c1a1\",\"name\":\"Administrador Site EMC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/emc.mg.gov.br\/institucional\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63af941dcc4c886e80dad58d5a5027c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63af941dcc4c886e80dad58d5a5027c6?s=96&d=mm&r=g\",\"caption\":\"Administrador Site EMC\"},\"url\":\"https:\/\/emc.mg.gov.br\/institucional\/author\/emc_adminweb\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Integrantes da banda Pato Fu no Agenda, da Rede Minas, nesta quarta (29) - EMC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/emc.mg.gov.br\/institucional\/integrantes-da-banda-pato-fu-no-agenda-da-rede-minas-nesta-quarta-29\/","og_locale":"pt_BR","og_type":"article","og_title":"Integrantes da banda Pato Fu no Agenda, da Rede Minas, nesta quarta (29) - EMC","og_description":"John Ulh\u00f4a e Richard Neves foram os convidados do Agenda, da Rede Minas. Os m\u00fasicos da banda Pato Fu falam sobre a participa\u00e7\u00e3o na trilha do filme \u201cO \u00daltimo Epis\u00f3dio&#8221;, da produtora \u201cFilmes de Pl\u00e1stico\u201d. A trilha sonora, assinada pelos integrantes do grupo, marca um ponto importante na carreira dos artistas e aposta nas mem\u00f3rias [&hellip;]","og_url":"http:\/\/emc.mg.gov.br\/institucional\/integrantes-da-banda-pato-fu-no-agenda-da-rede-minas-nesta-quarta-29\/","og_site_name":"EMC","article_published_time":"2025-10-29T17:55:29+00:00","article_modified_time":"2025-10-29T17:56:22+00:00","og_image":[{"width":300,"height":235,"url":"http:\/\/emc.mg.gov.br\/institucional\/wp-content\/uploads\/2025\/10\/THUMB-SITE-REDE-MINAS-E-EMC7-1.png","type":"image\/png"}],"author":"Administrador Site EMC","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Administrador Site EMC"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/emc.mg.gov.br\/institucional\/integrantes-da-banda-pato-fu-no-agenda-da-rede-minas-nesta-quarta-29\/#article","isPartOf":{"@id":"http:\/\/emc.mg.gov.br\/institucional\/integrantes-da-banda-pato-fu-no-agenda-da-rede-minas-nesta-quarta-29\/"},"author":{"name":"Administrador Site EMC","@id":"http:\/\/emc.mg.gov.br\/institucional\/#\/schema\/person\/b3c1372ae3ed1f53d53d7ebb7048c1a1"},"headline":"Integrantes da banda Pato Fu no Agenda, da Rede Minas, nesta quarta (29)","datePublished":"2025-10-29T17:55:29+00:00","dateModified":"2025-10-29T17:56:22+00:00","mainEntityOfPage":{"@id":"http:\/\/emc.mg.gov.br\/institucional\/integrantes-da-banda-pato-fu-no-agenda-da-rede-minas-nesta-quarta-29\/"},"wordCount":97,"commentCount":0,"publisher":{"@id":"http:\/\/emc.mg.gov.br\/institucional\/#organization"},"articleSection":["Destaques"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/emc.mg.gov.br\/institucional\/integrantes-da-banda-pato-fu-no-agenda-da-rede-minas-nesta-quarta-29\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/emc.mg.gov.br\/institucional\/integrantes-da-banda-pato-fu-no-agenda-da-rede-minas-nesta-quarta-29\/","url":"http:\/\/emc.mg.gov.br\/institucional\/integrantes-da-banda-pato-fu-no-agenda-da-rede-minas-nesta-quarta-29\/","name":"Integrantes da banda Pato Fu no Agenda, da Rede Minas, nesta quarta (29) - EMC","isPartOf":{"@id":"http:\/\/emc.mg.gov.br\/institucional\/#website"},"datePublished":"2025-10-29T17:55:29+00:00","dateModified":"2025-10-29T17:56:22+00:00","breadcrumb":{"@id":"http:\/\/emc.mg.gov.br\/institucional\/integrantes-da-banda-pato-fu-no-agenda-da-rede-minas-nesta-quarta-29\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/emc.mg.gov.br\/institucional\/integrantes-da-banda-pato-fu-no-agenda-da-rede-minas-nesta-quarta-29\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/emc.mg.gov.br\/institucional\/integrantes-da-banda-pato-fu-no-agenda-da-rede-minas-nesta-quarta-29\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/emc.mg.gov.br\/institucional\/"},{"@type":"ListItem","position":2,"name":"Integrantes da banda Pato Fu no Agenda, da Rede Minas, nesta quarta (29)"}]},{"@type":"WebSite","@id":"http:\/\/emc.mg.gov.br\/institucional\/#website","url":"http:\/\/emc.mg.gov.br\/institucional\/","name":"EMC","description":"Empresa Mineira de Comunica\u00e7\u00e3o","publisher":{"@id":"http:\/\/emc.mg.gov.br\/institucional\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/emc.mg.gov.br\/institucional\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"http:\/\/emc.mg.gov.br\/institucional\/#organization","name":"EMC","url":"http:\/\/emc.mg.gov.br\/institucional\/","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/emc.mg.gov.br\/institucional\/#\/schema\/logo\/image\/","url":"https:\/\/emc.mg.gov.br\/institucional\/wp-content\/uploads\/2022\/06\/EMCmarca.png","contentUrl":"https:\/\/emc.mg.gov.br\/institucional\/wp-content\/uploads\/2022\/06\/EMCmarca.png","width":133,"height":89,"caption":"EMC "},"image":{"@id":"http:\/\/emc.mg.gov.br\/institucional\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/emc.mg.gov.br\/institucional\/#\/schema\/person\/b3c1372ae3ed1f53d53d7ebb7048c1a1","name":"Administrador Site EMC","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/emc.mg.gov.br\/institucional\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63af941dcc4c886e80dad58d5a5027c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63af941dcc4c886e80dad58d5a5027c6?s=96&d=mm&r=g","caption":"Administrador Site EMC"},"url":"https:\/\/emc.mg.gov.br\/institucional\/author\/emc_adminweb\/"}]}},"_links":{"self":[{"href":"https:\/\/emc.mg.gov.br\/institucional\/wp-json\/wp\/v2\/posts\/3842"}],"collection":[{"href":"https:\/\/emc.mg.gov.br\/institucional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/emc.mg.gov.br\/institucional\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/emc.mg.gov.br\/institucional\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/emc.mg.gov.br\/institucional\/wp-json\/wp\/v2\/comments?post=3842"}],"version-history":[{"count":1,"href":"https:\/\/emc.mg.gov.br\/institucional\/wp-json\/wp\/v2\/posts\/3842\/revisions"}],"predecessor-version":[{"id":3844,"href":"https:\/\/emc.mg.gov.br\/institucional\/wp-json\/wp\/v2\/posts\/3842\/revisions\/3844"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emc.mg.gov.br\/institucional\/wp-json\/wp\/v2\/media\/3845"}],"wp:attachment":[{"href":"https:\/\/emc.mg.gov.br\/institucional\/wp-json\/wp\/v2\/media?parent=3842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/emc.mg.gov.br\/institucional\/wp-json\/wp\/v2\/categories?post=3842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/emc.mg.gov.br\/institucional\/wp-json\/wp\/v2\/tags?post=3842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}